{"id":95571,"date":"2026-07-14T19:21:10","date_gmt":"2026-07-14T22:21:10","guid":{"rendered":"https:\/\/portalnpm.com\/?p=95571"},"modified":"2026-07-14T19:21:10","modified_gmt":"2026-07-14T22:21:10","slug":"espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo","status":"publish","type":"post","link":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/","title":{"rendered":"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo"},"content":{"rendered":"<header class=\"md-12 sm-8 xs-4\"><\/header>\n<article class=\"md-8 sm-8 xs-4 article-body\" data-mg-article-url=\"https:\/\/jogada10.com.br\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\">Depois de 16 anos, a Espanha est\u00e1 de volta a uma final de Copa do Mundo. Com uma atua\u00e7\u00e3o praticamente perfeita em todos os cantos do campo, a Espanha superou \u2013 mais uma vez \u2013 a Fran\u00e7a, dessa vez por 2 a 0, e est\u00e1 classificada para a grande decis\u00e3o do Mundial, no pr\u00f3ximo domingo, dia 19, no Metlife Stadium, em Nova York. Oyarzabal, no primeiro tempo, e Pedro Porro, no segundo, marcaram os gols que carimbaram o passaporte espanhol para a final da Copa.<\/p>\n<p>Agora, a Espanha vai assistir de camarote a segunda semifinal da Copa do Mundo nesta quarta. Em Atlanta, Inglaterra e Argentina medem for\u00e7as, \u00e0s 16h, pela segunda vaga na grande final.<\/p>\n<h2>La Roja na frente<\/h2>\n<p>O constraste de estilos colocados frente \u00e0 frente em Dallas era a grande hist\u00f3ria desta semifinal. E um dos protagonistas da partida apareceu logo aos 20 minutos. Lamine Yamal levou vantagem em dividida com Digne, foi derrubado dentro da \u00e1rea e o\u00a0 \u00e1rbitro Ivan Barton apontou para a marca da cal. Na cobran\u00e7a, Oyarzabal n\u00e3o titubeou e converteu a penalidade em favor da Espanha, que saiu na frente do placar.<\/p>\n<figure id=\"attachment_1205959\" class=\"wp-caption aligncenter\" aria-labelledby=\"figcaption_attachment_1205959\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-1205959 img-responsive entered lazyloaded\" src=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_.jpg\" sizes=\"(max-width: 1280px) 100vw, 1280px\" srcset=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_.jpg 1280w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-300x200.jpg 300w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-1024x682.jpg 1024w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-768x512.jpg 768w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-711x474.jpg 711w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-150x100.jpg 150w\" alt=\"\" width=\"1280\" height=\"853\" data-lazy-srcset=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_.jpg 1280w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-300x200.jpg 300w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-1024x682.jpg 1024w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-768x512.jpg 768w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-711x474.jpg 711w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_-150x100.jpg 150w\" data-lazy-sizes=\"(max-width: 1280px) 100vw, 1280px\" data-lazy-src=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNlz1_XcAAqt_b_Easy-Resize.com_.jpg\" data-ll-status=\"loaded\" \/><figcaption id=\"figcaption_attachment_1205959\" class=\"wp-caption-text\">Espanha venceu a Fran\u00e7a e se classificou para a final da Copa do Mundo \u2013 Foto: Divulga\u00e7\u00e3o \/ SEFutbol<\/figcaption><\/figure>\n<h2>Fran\u00e7a tenta reagir<\/h2>\n<p>Pela primeira vez na Copa do Mundo, a Fran\u00e7a se viu atr\u00e1s no placar e tendo que buscar o resultado. Curiosamente, justamente no jogo mais decisivo da Copa do Mundo at\u00e9 aqui. No entanto, a defesa espanhola \u2013 que chegou nesta partida com apenas um gol sofrido \u2013 conseguiu segurar o \u00edmpeto do talentoso ataque franc\u00eas. Demb\u00e9l\u00e9 e Mbapp\u00e9, que combinaram para 13 gols na Copa, pouco conseguiram fazer para levar perigo, enquanto Michel Olise, maior assistente da Copa at\u00e9 aqui, ficou preso na marca\u00e7\u00e3o e pouco acrescentou.<\/p>\n<h2>Vantagem dobrada<\/h2>\n<p>Na volta do intervalo, a Fran\u00e7a trouxe sangue novo para o meio de campo com a entrada de Kon\u00e9 no lugar de Rabiot, com a ideia de fazer o jogo ser mais controlado na faixa central do gramado. Contudo, a Espanha n\u00e3o mudou seu estilo e nem o seu ritmo para segurar o resultado. Pelo contr\u00e1rio, La Roja aproveitou a chance que teve para aumentar a vantagem no placar. Olmo deslocou belo passe para Pedro Porro, que saiu frente a frente com Maignan e tocou na sa\u00edda do goleiro para fazer o segundo aos 13 minutos.<\/p>\n<figure id=\"attachment_1206009\" class=\"wp-caption aligncenter\" aria-labelledby=\"figcaption_attachment_1206009\"><img decoding=\"async\" class=\"size-full wp-image-1206009 img-responsive entered lazyloaded\" src=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_.jpg\" sizes=\"(max-width: 1280px) 100vw, 1280px\" srcset=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_.jpg 1280w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-300x200.jpg 300w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-1024x682.jpg 1024w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-768x512.jpg 768w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-711x474.jpg 711w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-150x100.jpg 150w\" alt=\"\" width=\"1280\" height=\"853\" data-lazy-srcset=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_.jpg 1280w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-300x200.jpg 300w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-1024x682.jpg 1024w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-768x512.jpg 768w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-711x474.jpg 711w, https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_-150x100.jpg 150w\" data-lazy-sizes=\"(max-width: 1280px) 100vw, 1280px\" data-lazy-src=\"https:\/\/jogada10.com.br\/wp-content\/uploads\/2026\/07\/HNNxTGSW0AABOlf_Easy-Resize.com_.jpg\" data-ll-status=\"loaded\" \/><figcaption id=\"figcaption_attachment_1206009\" class=\"wp-caption-text\">Pedro Porro marcou o segundo gol da Espanha na partida \u2013 Foto: Divulga\u00e7\u00e3o \/ SEFutbol<\/figcaption><\/figure>\n<h2>Tudo para a Espanha, nada para a Fran\u00e7a<\/h2>\n<p>Se a Fran\u00e7a n\u00e3o tinha ficado atr\u00e1s do placar nesta Copa, com dois gols de desvantagem o cen\u00e1rio ficou ainda pior. Os franceses se lan\u00e7aram ao ataque em busca de um gol, mas o que se viu foi uma Espanha armada para matar de vez a partida. Lamine Yamal, inclusive, chegou a marcar o terceiro, mas o gol foi anulado pelo VAR. Mbapp\u00e9 n\u00e3o teve uma grande chance e foi o s\u00edmbolo da frustra\u00e7\u00e3o nos minutos finais, com um pontap\u00e9 no goleiro Unai Sim\u00f3n e uma cobran\u00e7a de falta por cima do gol. Demb\u00e9l\u00e9, melhor jogador do mundo em 2025, tamb\u00e9m parou em Unai Sim\u00f3n, que enterrou de vez as chances de uma rea\u00e7\u00e3o francesa. Sendo assim, classifica\u00e7\u00e3o espanhola para a final!<\/p>\n<p>&nbsp;<\/p>\n<h2 dir=\"ltr\"><strong>FRAN\u00c7A 0x2 ESPANHA<\/strong><\/h2>\n<p dir=\"ltr\"><strong>Copa do Mundo \u2013 semifinal<br \/>\n<\/strong><strong>Data e hor\u00e1rio<\/strong>: 14\/07\/2025 (ter\u00e7a-feira), \u00e0s 16h (de Bras\u00edlia)<br \/>\n<strong>Local<\/strong>: AT&amp;T Stadium, Dallas (EUA)<br \/>\n<strong>P\u00fablico:\u00a0<\/strong>70.176 pessoas<strong><br \/>\nGols<\/strong>: Oyarzabal (22\u2019\/1T, 0-1), Pedro Porro (13\u2019\/2T, 0-2)<br \/>\n<strong>FRAN\u00c7A<\/strong>: Maignan; Kound\u00e9, Upamecano, Saliba (Lacroix, 30\u2019\/1T) e Lucas Digne (Theo Hern\u00e1ndez, 27\u2019\/2T); Tchou\u00e1meni, Rabiot (Kone, intervalo) e Olise (Cherki, 27\u2019\/2T); Barcola (Dou\u00e9, 12\u2019\/2T), Demb\u00e9l\u00e9, Mbapp\u00e9.\u00a0<strong>T\u00e9cnico<\/strong>: Didier Deschamps.<br class=\"yoast-text-mark\" \/>&gt;<strong>ESPANHA<\/strong>: Unai Sim\u00f3n; Pedro Porro (Llorente, 39\u2019\/2T), Pau Cubars\u00ed, Laporte e Cucurella; Rodri, Fabi\u00e1n Ruiz (Pedri, 33\u2019\/2T) e Dani Olmo (Merino, 33\u2019\/2T); \u00c1lex Baena (Nico Williams, 39\u2019\/2T), Lamine Yamal, Oyarzabal (Ferran Torres, 29\u2019\/2T).\u00a0<strong>T\u00e9cnico<\/strong>: Luis de la Fuente.<br \/>\n<strong>\u00c1rbitro<\/strong>: Ivan Barton (ELS)<br \/>\n<strong>Assistentes<\/strong>: David Moran (ELS) e Antonio Pupiro (NIC)<br \/>\n<strong>VAR<\/strong>: Tomasz Kwiatkowski (POL)<br \/>\n<strong>Cart\u00f5es Amarelos:\u00a0<\/strong>Rabiot, Mbapp\u00e9 (FRA), Cucurella (<\/p>\n<p dir=\"ltr\">Fonte: Jogada 10<\/p>\n<\/article>\n","protected":false},"excerpt":{"rendered":"<p>Depois de 16 anos, a Espanha est\u00e1 de volta a uma final de Copa do Mundo. Com uma atua\u00e7\u00e3o praticamente perfeita em todos os cantos do campo, a Espanha superou \u2013 mais uma vez \u2013 a Fran\u00e7a, dessa vez por 2 a 0, e est\u00e1 classificada para a grande decis\u00e3o do Mundial, no pr\u00f3ximo domingo, &hellip;<\/p>\n","protected":false},"author":2,"featured_media":95572,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"content-type":"","rop_custom_images_group":[],"rop_custom_messages_group":[],"rop_publish_now":"no","rop_publish_now_accounts":{"facebook_2648258775420054_1618374048415101":""},"rop_publish_now_history":[{"account":"facebook_2648258775420054_1618374048415101","service":"facebook","timestamp":1784067695,"status":"success"}],"rop_publish_now_status":"done","footnotes":"","_jetpack_memberships_contains_paid_content":false},"categories":[113,108],"tags":[837,836,11701,4032,658,3045,3733,832,3138,911,11137,140],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM\" \/>\n<meta property=\"og:description\" content=\"Depois de 16 anos, a Espanha est\u00e1 de volta a uma final de Copa do Mundo. Com uma atua\u00e7\u00e3o praticamente perfeita em todos os cantos do campo, a Espanha superou \u2013 mais uma vez \u2013 a Fran\u00e7a, dessa vez por 2 a 0, e est\u00e1 classificada para a grande decis\u00e3o do Mundial, no pr\u00f3ximo domingo, &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"Portal NPM\" \/>\n<meta property=\"article:published_time\" content=\"2026-07-14T22:21:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"855\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Genival Barbosa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Genival Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\",\"url\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\",\"name\":\"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM\",\"isPartOf\":{\"@id\":\"https:\/\/portalnpm.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg\",\"datePublished\":\"2026-07-14T22:21:10+00:00\",\"dateModified\":\"2026-07-14T22:21:10+00:00\",\"author\":{\"@id\":\"https:\/\/portalnpm.com\/#\/schema\/person\/49313e563cfdefcc167f1ee4c017c294\"},\"breadcrumb\":{\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage\",\"url\":\"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg\",\"contentUrl\":\"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg\",\"width\":1280,\"height\":855},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\/\/portalnpm.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/portalnpm.com\/#website\",\"url\":\"https:\/\/portalnpm.com\/\",\"name\":\"Portal NPM\",\"description\":\"Not\u00edcias em Primeira M\u00e3o\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/portalnpm.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/portalnpm.com\/#\/schema\/person\/49313e563cfdefcc167f1ee4c017c294\",\"name\":\"Genival Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\/\/portalnpm.com\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/portalnpm.com\/wp-content\/uploads\/2024\/02\/avatar_user_2_1707743258-96x96.jpeg\",\"contentUrl\":\"https:\/\/portalnpm.com\/wp-content\/uploads\/2024\/02\/avatar_user_2_1707743258-96x96.jpeg\",\"caption\":\"Genival Barbosa\"},\"url\":\"https:\/\/portalnpm.com\/index.php\/author\/genival\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/","og_locale":"pt_BR","og_type":"article","og_title":"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM","og_description":"Depois de 16 anos, a Espanha est\u00e1 de volta a uma final de Copa do Mundo. Com uma atua\u00e7\u00e3o praticamente perfeita em todos os cantos do campo, a Espanha superou \u2013 mais uma vez \u2013 a Fran\u00e7a, dessa vez por 2 a 0, e est\u00e1 classificada para a grande decis\u00e3o do Mundial, no pr\u00f3ximo domingo, &hellip;","og_url":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/","og_site_name":"Portal NPM","article_published_time":"2026-07-14T22:21:10+00:00","og_image":[{"width":1280,"height":855,"url":"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg","type":"image\/jpeg"}],"author":"Genival Barbosa","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Genival Barbosa","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/","url":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/","name":"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo - Portal NPM","isPartOf":{"@id":"https:\/\/portalnpm.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg","datePublished":"2026-07-14T22:21:10+00:00","dateModified":"2026-07-14T22:21:10+00:00","author":{"@id":"https:\/\/portalnpm.com\/#\/schema\/person\/49313e563cfdefcc167f1ee4c017c294"},"breadcrumb":{"@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#primaryimage","url":"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg","contentUrl":"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg","width":1280,"height":855},{"@type":"BreadcrumbList","@id":"https:\/\/portalnpm.com\/index.php\/2026\/07\/14\/espanha-faz-jogo-perfeito-vence-a-franca-e-esta-na-final-da-copa-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/portalnpm.com\/"},{"@type":"ListItem","position":2,"name":"Espanha faz jogo perfeito, vence a Fran\u00e7a e est\u00e1 na final da Copa do Mundo"}]},{"@type":"WebSite","@id":"https:\/\/portalnpm.com\/#website","url":"https:\/\/portalnpm.com\/","name":"Portal NPM","description":"Not\u00edcias em Primeira M\u00e3o","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/portalnpm.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"Person","@id":"https:\/\/portalnpm.com\/#\/schema\/person\/49313e563cfdefcc167f1ee4c017c294","name":"Genival Barbosa","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/portalnpm.com\/#\/schema\/person\/image\/","url":"https:\/\/portalnpm.com\/wp-content\/uploads\/2024\/02\/avatar_user_2_1707743258-96x96.jpeg","contentUrl":"https:\/\/portalnpm.com\/wp-content\/uploads\/2024\/02\/avatar_user_2_1707743258-96x96.jpeg","caption":"Genival Barbosa"},"url":"https:\/\/portalnpm.com\/index.php\/author\/genival\/"}]}},"jetpack_sharing_enabled":true,"jetpack_featured_media_url":"https:\/\/portalnpm.com\/wp-content\/uploads\/2026\/07\/HNNjwtWW0AAmGFw_Easy-Resize.com_.jpg","_links":{"self":[{"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/posts\/95571"}],"collection":[{"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/comments?post=95571"}],"version-history":[{"count":1,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/posts\/95571\/revisions"}],"predecessor-version":[{"id":95573,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/posts\/95571\/revisions\/95573"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/media\/95572"}],"wp:attachment":[{"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/media?parent=95571"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/categories?post=95571"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/portalnpm.com\/index.php\/wp-json\/wp\/v2\/tags?post=95571"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}